{"id":822,"date":"2023-11-13T22:25:53","date_gmt":"2023-11-13T21:25:53","guid":{"rendered":"http:\/\/nmmassage.fr\/?page_id=822"},"modified":"2024-11-07T10:51:28","modified_gmt":"2024-11-07T09:51:28","slug":"contact-2","status":"publish","type":"page","link":"https:\/\/nmmassage.fr\/index.php\/contact-2\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"822\" class=\"elementor elementor-822\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ffe5755 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"ffe5755\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ecba0b6 exad-glass-effect-no exad-sticky-section-no\" data-id=\"ecba0b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-954abfd elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"954abfd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-29e03e7 exad-glass-effect-no exad-sticky-section-no\" data-id=\"29e03e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da80362 elementor-widget__width-initial exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"da80362\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nmmassage.fr\/wp-content\/uploads\/elementor\/thumbs\/Contact-e1706205062812-qiuaboz84fqnl65bexcunfl661alc79ex7xm0336qk.png\" title=\"Contact\" alt=\"Contact\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74d0371 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"74d0371\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-887705b exad-glass-effect-no exad-sticky-section-no\" data-id=\"887705b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d53dc8 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"9d53dc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Vous souhaitez prendre un rendez-vous rapidement ?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-600408d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"600408d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-098bfb9 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"098bfb9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1c62d9d exad-glass-effect-no exad-sticky-section-no\" data-id=\"1c62d9d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04e38ed elementor-widget__width-initial exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"04e38ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nmmassage.fr\/wp-content\/uploads\/elementor\/thumbs\/4-e1705440358482-qievp8t9o0ec1aib2np60sizb62zqb0ge4alebmr3k.png\" title=\"4\" alt=\"4\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b93ffbe exad-glass-effect-no exad-sticky-section-no\" data-id=\"b93ffbe\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-651427a elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"651427a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-55c5bb1 exad-glass-effect-no exad-sticky-section-no\" data-id=\"55c5bb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f37c47d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"f37c47d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9servez votre massage directement en ligne !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27fb72d elementor-widget__width-initial exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"27fb72d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9couvrez les cr\u00e9neaux disponibles et r\u00e9servez votre massage en \u00e0 peine 5 minutes gr\u00e2ce \u00e0 Calendly ! Une fois votre demande r\u00e9alis\u00e9e vous recevrez un mail de confirmation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7911498 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"7911498\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb23abf elementor-widget__width-initial exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-exad-modal-popup\" data-id=\"bb23abf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"exad-modal-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\r\n\t\t<div class=\"exad-modal\">\r\n\t\t\t<div class=\"exad-modal-wrapper\">\r\n\r\n\t\t\t\t<div class=\"exad-modal-button exad-modal-btn-fixed-width-\">\r\n\t\t\t\t\t<a href=\"#\" class=\"exad-modal-image-action image-modal\" data-exad-modal=\"#exad-modal-bb23abf\" data-exad-overlay=\"yes\" >\r\n\t\t\t\t\t\t<span class=\"exad-modal-action-icon-\">\r\n\t\t\t\t\t\t\tR\u00e9server\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/div>\r\n\t\t\r\n\t\t\t\t<div id=\"exad-modal-bb23abf\" class=\"exad-modal-item modal-vimeo modal-vimeo-img-fluid zoom-out external_page exad-content-overflow-x-yes exad-content-overflow-y-yes\" data-exad_modal_prevent_page_scroll=\"no\" >\r\n\t\t\t\t\t<div class=\"exad-modal-content\">\r\n\t\t\t\t\t\t<div class=\"exad-modal-element \">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<iframe src=\"https:\/\/calendly.com\/nmmassage-pro\/reservation\" frameborder=\"0\" allowfullscreen ><\/iframe>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"exad-close-btn\">\r\n\t\t\t\t\t\t\t\t<span><\/span>\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"exad-modal-overlay\" data-exad_overlay_click_close=\"yes\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-741e497 exad-glass-effect-no exad-sticky-section-no\" data-id=\"741e497\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85993a1 elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"85993a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df1080c exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"df1080c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nmmassage.fr\/wp-content\/uploads\/elementor\/thumbs\/Calendrier-e1706207565646-qiuc51p946dz4xlfs908h3fnxyb7eq0vqxyulelfz0.png\" title=\"Calendrier\" alt=\"Calendrier\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d4c3d4 elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"1d4c3d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c5a928 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"0c5a928\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-360505e exad-glass-effect-no exad-sticky-section-no\" data-id=\"360505e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc683ec elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"cc683ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80aa517 elementor-widget__width-initial exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-shortcode\" data-id=\"80aa517\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><pre class=\"ti-widget\" style=\"display: none\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-time-locale=\"il y a %d %s|aujourd&apos;hui|jour|jours|semaine|semaines|mois|mois|ann\u00e9e|ans\" data-plugin-version=\"13.3.2\" data-layout-id=\"5\" data-layout-category=\"slider\" data-set-id=\"light-background\" data-pid=\"\" data-language=\"fr\" data-close-locale=\"Fermer\" data-review-target-width=\"275\" data-css-version=\"2\" data-reply-by-locale=\"R\u00e9ponse du propri\u00e9taire\" data-only-rating-locale=\"Cet utilisateur a uniquement laiss\u00e9 une \u00e9valuation.\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-4\"> <div class=\"ti-footer ti-footer-grid source-Google\"> <div class=\"ti-fade-container\"> <div class=\"ti-rating-text\"> <strong class=\"ti-rating ti-rating-large\"> EXCELLENT <\/strong> <\/div> <span class=\"ti-stars star-lg\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-rating-text\"> <span class=\"nowrap\">Bas\u00e9e sur <strong>51 avis<\/strong><\/span> <\/div> <div class=\"ti-large-logo\"> <div class=\"ti-v-center\"> <trustindex-image class=\"ti-logo-fb\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/logo.svg\" width=\"150\" height=\"25\" loading=\"lazy\" alt=\"Google\"><\/trustindex-image> <\/div> <\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Avis suivante\" role=\"button\" tabindex=\"0\"><\/div> <div class=\"ti-prev\" aria-label=\"Avis pr\u00e9c\u00e9dent\" role=\"button\" tabindex=\"0\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" data-time=\"1704844800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIiskzHCNtWbJzeGp3tPwqA_oAkVLG3oDIBB7sguqYd=w40-h40-c-rp-mo-br100\" alt=\"Hugo METIFIOT profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Hugo METIFIOT <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Je recommande, moment de d\u00e9tente assur\u00e9 !<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1700524800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjV0sYcUYEZT7PuDL_BNORh4WEKap7nOb8XHFLi4YaxFjwo=w40-h40-c-rp-mo-br100\" alt=\"B. Katy profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> B. Katy <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Tr\u00e8s belle exp\u00e9rience. Nicolas s\u2019adapte parfaitement \u00e0 la demande, tr\u00e8s professionnel et \u00e0 l\u2019\u00e9coute. J\u2019avais du mal \u00e0 m\u2019endormir \u00e0 cause de mes probl\u00e8mes cervicales mais avec ses mains magiques apr\u00e8s 1 s\u00e9ance j\u2019ai pass\u00e9 une tr\u00e8s bonne nuit et \u00e7a m\u2019a d\u00e9tendu. Merci Nicolas \ud83d\ude42\nJe recommande \u00e0 1000%<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1693267200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocI4pIm65ghNbGHErDvcFPzNgbn40piCSCadhENPuKBWTA=w40-h40-c-rp-mo-br100\" alt=\"Laird Brice profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Laird Brice <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Super exp\u00e9rience !!! Un vrai moment de d\u00e9tente. Nicolas est accueillant, professionnel et \u00e0 l'\u00e9coute du corps.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1691452800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJzP-Flqz8DOvMEIzTxNUlcM8YKuaekON763zSFWxMX=w40-h40-c-rp-mo-br100\" alt=\"Olivier Chovin profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Olivier Chovin <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Un service de grande qualit\u00e9 et vraiment \u00e0 l'\u00e9coute du patient. Que ce soit pour un massage d\u00e9tente, ou pour travailler sur des points musculaires pr\u00e9cis, notamment li\u00e9 \u00e0 la pratique du sport, Nico prend vraiment le temps d'\u00e9couter et d'adapter les s\u00e9ances en fonction de vos besoins. Le passage au salon est d\u00e9sormais un rendez-vous r\u00e9gulier pour moi, notamment pour la qualit\u00e9 des massages bien entendu, mais aussi du suivi. Les prix sont par ailleurs plus que convenables pour le service re\u00e7u en retour.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1689379200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLeXacmmd7GXPOE7sWn_yIvAUApxoWl2S9hLfRzL8gO=w40-h40-c-rp-mo-br100\" alt=\"R\u00e9mi Laffont profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> R\u00e9mi Laffont <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Le ma\u00eetre des noeuds rien \u00e0 redire, professionnel tr\u00e8s disponible \u00e0 la r\u00e9ponse de tout g\u00e9nialissime j\u2019ai pas les mots \u00e0 d\u00e9couvrir<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1687046400\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXch6f0-ilnuaoaMIoGT0j3rq9wmfz92jEynH3vr3xOVTs=w40-h40-c-rp-mo-br100\" alt=\"Michele Sottile profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Michele Sottile <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->J'ai contact\u00e9 Nicolas avec des demandes tr\u00e8s pr\u00e9cises et il a litt\u00e9ralement d\u00e9pass\u00e9 mes attentes les plus \u00e9lev\u00e9es. Lui-m\u00eame sportif et professionnel de grand talent, il a su allier d\u00e9tente et remise en forme, gr\u00e2ce \u00e0 une ambiance accueillante et une grande propension \u00e0 l' \u00e9coute du client et de son corps. Sympathie, passion pour son travail et extr\u00eame disponibilit\u00e9 sont ses autres qualit\u00e9s qui ont rendu l'exp\u00e9rience vraiment agr\u00e9able et surtout efficace. J'attends d\u00e9j\u00e0 avec impatience notre prochaine rencontre.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1683244800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWw3bO8IcqkxDBnrABowoltmjlX7e4sA8HFkPGhspa-4E0=w40-h40-c-rp-mo-ba2-br100\" alt=\"Fanny Bombrun profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Fanny Bombrun <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Nicolas est professionnel et \u00e0 l'\u00e9coute, il s'est adapt\u00e9 le massage en fonction de la demande.\nJ'ai \u00e9t\u00e9 ravi de d\u00e9couvrir le massage su\u00e9dois, un vrai moment de d\u00e9tente dans une atmosph\u00e8re enveloppante.\nJe reviendrai c'est s\u00fbr \ud83d\ude09<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1682726400\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXT2iJlPjGD3__-K3sGSucKMhD5sPkGR5GtnNh6JmPj4ok=w40-h40-c-rp-mo-ba5-br100\" alt=\"Christophe Toto profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Christophe Toto <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Nicolas M. ma\u00eetrise plusieurs techniques de massage, il est \u00e0 l'\u00e9coute et personnalise chaque prestation. A son cabinet, j'ai fait l'exp\u00e9rience d'un massage de r\u00e9cup\u00e9ration qui s'est av\u00e9r\u00e9 \u00eatre agr\u00e9able et efficace. Les noeuds musculaires sont d\u00e9nou\u00e9s, on retrouve de l'\u00e9lasticit\u00e9 et l'effet drainant favorise l'\u00e9limination des toxines. Sportif de haut niveau, son exp\u00e9rience en le domaine vient parfaitement compl\u00e9ter ses talents, il sait de quoi il parle. Nicolas peut aussi se d\u00e9placer, \u00e0 domicile ou autre. Ce qui est int\u00e9ressant pour b\u00e9n\u00e9ficier de ses services sur un \u00e9v\u00e8nement sportif ou en entreprise.\nL\u00e2chez prise et confiez votre bien-\u00eatre \u00e0 un professionnel.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1679529600\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKE6OUjrFn3BsPmW3XIGZeUBnu5VipEhBasl3kWIlgO=w40-h40-c-rp-mo-br100\" alt=\"Camille GAILLARD profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Camille GAILLARD <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Super moment de d\u00e9tente en duo en fin de semaine pour attaque un week-end en \u00e9tant pleinement repos\u00e9.\nNous avons \u00e9t\u00e9 super bien re\u00e7u, aucun bruit environnement pour profiter pleinement du moment.\nMerci \u00e0 tous les 2<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div>   <\/div> <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/nmmassage.fr\/wp-content\/uploads\/trustindex-google-widget.css?1787088109\"><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66dabda elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"66dabda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66d6314 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"66d6314\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50a878a exad-glass-effect-no exad-sticky-section-no\" data-id=\"50a878a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ede91f exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"4ede91f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Vous avez des questions ou une demande particuli\u00e8re ?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76abde1 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"76abde1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0bd74f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"0bd74f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d1cd5c3 exad-glass-effect-no exad-sticky-section-no\" data-id=\"d1cd5c3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-545b870 elementor-widget__width-initial exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"545b870\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nmmassage.fr\/wp-content\/uploads\/elementor\/thumbs\/4-e1705440358482-qievp8t9o0ec1aib2np60sizb62zqb0ge4alebmr3k.png\" title=\"4\" alt=\"4\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6352b47 exad-glass-effect-no exad-sticky-section-no\" data-id=\"6352b47\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8a227bc elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"8a227bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5676cf1 exad-glass-effect-no exad-sticky-section-no\" data-id=\"5676cf1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47a2b9c elementor-widget__width-initial exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"47a2b9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contactez-nous directement via ce formulaire !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2c251d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"a2c251d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad0186e elementor-widget__width-initial exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-everest-forms\" data-id=\"ad0186e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"everest-forms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"everest-forms\"><div class=\"evf-container default\" id=\"evf-834\"><form id=\"evf-form-834\" class=\"everest-form\" data-formid=\"834\" data-ajax_submission=\"0\" data-keyboard_friendly_form=\"0\" data-form_state_type=\"\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/822\"><div class=\"evf-field-container\"><input type=\"hidden\" id=\"_wpnonce834\" name=\"_wpnonce834\" value=\"df8f178bb0\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/index.php\/wp-json\/wp\/v2\/pages\/822\" \/><div class=\"evf-frontend-row\" data-row=\"row_2\" conditional_rules=\"[]\"><div class=\"evf-frontend-grid evf-grid-2\" data-grid=\"grid_1\"><div id=\"evf-834-field_1SrOJDOan1-4-container\" class=\"evf-field evf-field-first-name form-row validate-required\" data-required-field-message=\"Ce champ est n\u00e9cessaire.\" data-field-id=\"1SrOJDOan1-4\"><label class=\"evf-field-label\" for=\"evf-834-field_1SrOJDOan1-4\"><span class=\"evf-label\">Pr\u00e9nom<\/span> <abbr class=\"required\" title=\"N\u00e9cessaire\">*<\/abbr><\/label><input type=\"text\" id=\"evf-834-field_1SrOJDOan1-4\" class=\"input-text\" name=\"everest_forms[form_fields][1SrOJDOan1-4]\" required><\/div><div id=\"evf-834-field_TL6fKFTBCL-5-container\" class=\"evf-field evf-field-last-name form-row validate-required\" data-required-field-message=\"Ce champ est n\u00e9cessaire.\" data-field-id=\"TL6fKFTBCL-5\"><label class=\"evf-field-label\" for=\"evf-834-field_TL6fKFTBCL-5\"><span class=\"evf-label\">Nom<\/span> <abbr class=\"required\" title=\"N\u00e9cessaire\">*<\/abbr><\/label><input type=\"text\" id=\"evf-834-field_TL6fKFTBCL-5\" class=\"input-text\" name=\"everest_forms[form_fields][TL6fKFTBCL-5]\" required><\/div><\/div><div class=\"evf-frontend-grid evf-grid-2\" data-grid=\"grid_2\"><div id=\"evf-834-field_9m0rNPAgiU-1-container\" class=\"evf-field evf-field-email form-row validate-required validate-email\" data-required-field-message=\"Veuillez entrer une adresse e-mail valide.\" data-field-id=\"9m0rNPAgiU-1\"><label class=\"evf-field-label\" for=\"evf-834-field_9m0rNPAgiU-1\"><span class=\"evf-label\">E-mail<\/span> <abbr class=\"required\" title=\"N\u00e9cessaire\">*<\/abbr><\/label><input type=\"email\" id=\"evf-834-field_9m0rNPAgiU-1\" class=\"input-text\" name=\"everest_forms[form_fields][9m0rNPAgiU-1]\" required ><\/div><div id=\"evf-834-field_29tqnrALsj-2-container\" class=\"evf-field evf-field-select form-row validate-required\" data-required-field-message=\"Ce champ est n\u00e9cessaire.\" data-field-id=\"29tqnrALsj-2\"><label class=\"evf-field-label\" for=\"evf-834-field_29tqnrALsj-2\"><span class=\"evf-label\">Choisissez un sujet<\/span> <abbr class=\"required\" title=\"N\u00e9cessaire\">*<\/abbr><\/label><select id=\"evf-834-field_29tqnrALsj-2\" class=\"input-text evf-field-required\" name=\"everest_forms[form_fields][29tqnrALsj-2]\" required=\"required\" ><option value=\"Demande sp\u00e9cifique\" >Demande sp\u00e9cifique<\/option><option value=\"R\u00e9server un massage\" >R\u00e9server un massage<\/option><option value=\"Offrir un massage\" >Offrir un massage<\/option><option value=\"Suivi de sportif\" >Suivi de sportif<\/option><option value=\"Massage pour les \u00e9v\u00e8nements\" >Massage pour les \u00e9v\u00e8nements<\/option><option value=\"Massage pour les entrpreises\" >Massage pour les entrpreises<\/option><option value=\"Autres\" >Autres<\/option><\/select><\/div><\/div><\/div><div class=\"evf-frontend-row\" data-row=\"row_1\" conditional_rules=\"[]\"><div class=\"evf-frontend-grid evf-grid-1\" data-grid=\"grid_1\"><div id=\"evf-834-field_IH0hQeFINB-3-container\" class=\"evf-field evf-field-textarea form-row validate-required\" data-required-field-message=\"Ce champ est n\u00e9cessaire.\" data-field-id=\"IH0hQeFINB-3\"><label class=\"evf-field-label\" for=\"evf-834-field_IH0hQeFINB-3\"><span class=\"evf-label\">Message<\/span> <abbr class=\"required\" title=\"N\u00e9cessaire\">*<\/abbr><\/label><textarea id=\"evf-834-field_IH0hQeFINB-3\" class=\"input-text\" name=\"everest_forms[form_fields][IH0hQeFINB-3]\" required ><\/textarea><\/div><\/div><\/div><\/div><div class=\"evf-honeypot-container evf-field-hp\"><label for=\"evf-834-field-hp\" class=\"evf-field-label\">Name<\/label><input type=\"text\" name=\"everest_forms[hp]\" id=\"evf-834-field-hp\" class=\"input-text\"><\/div><div class=\"evf-submit-container \" ><input type=\"hidden\" name=\"everest_forms[id]\" value=\"834\"><input type=\"hidden\" name=\"everest_forms[author]\" value=\"1\"><button type='submit' name='everest_forms[submit]' class='everest-forms-submit-button button evf-submit ' id='evf-submit-834' value='evf-submit' data-process-text=\"En traitement\u2026\" conditional_rules='&quot;&quot;' conditional_id='evf-submit-834'  id=\"evf-submit-834\" aria-live=\"assertive\">Valider<\/button><\/div><\/form><\/div><!-- .evf-container --><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3101607 exad-glass-effect-no exad-sticky-section-no\" data-id=\"3101607\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b4d24d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"1b4d24d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Questions fr\u00e9quentes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1fbbcd exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-eael-adv-accordion\" data-id=\"a1fbbcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-adv-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"eael-adv-accordion\" id=\"eael-adv-accordion-a1fbbcd\" data-scroll-on-click=\"no\" data-scroll-speed=\"300\" data-accordion-id=\"a1fbbcd\" data-accordion-type=\"accordion\" data-toogle-speed=\"300\">\n            <div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"comment-offrir-un-massage-\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"1\" aria-controls=\"elementor-tab-content-1691\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">Comment offrir un massage ?<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1691\" class=\"eael-accordion-content clearfix\" data-tab=\"1\" aria-labelledby=\"comment-offrir-un-massage-\"><p>Pour offrir un massage, allez sur <a href=\"https:\/\/nmmassage.fr\/index.php\/offres\/\"><span style=\"text-decoration: underline\"><span style=\"color: #ffffff;text-decoration: underline\">la page Offres<\/span><\/span><\/a>\u00a0et choisissez la carte cadeau qui vous convient : Anniversaire ; Saint Valentin ; No\u00ebl&#8230;<\/p><p>Une fois la carte cadeau choisie, remplissez le formulaire<strong> en 5 minutes<\/strong> : Quel type de massage ? ; Combien de temps ? ; Pour &#8230; ; De la part de &#8230; et voil\u00e0 <strong>votre carte cadeau massage est r\u00e9serv\u00e9e !<\/strong><\/p><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"comment-se-droule-une-sance-\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"2\" aria-controls=\"elementor-tab-content-1692\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">Comment se d\u00e9roule une s\u00e9ance ?<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1692\" class=\"eael-accordion-content clearfix\" data-tab=\"2\" aria-labelledby=\"comment-se-droule-une-sance-\"><p><em>En amont\u200b<\/em><br \/><b>N<\/b><strong>ous commen\u00e7ons par<\/strong> <strong>entretien priv\u00e9 afin de comprendre vos envies et vos besoins.\u00a0<\/strong>\u00c0 la fin de l&rsquo;entretien <strong>choisissez parmi diff\u00e9rentes huiles de massage <\/strong>selon vos pr\u00e9f\u00e9rences.<\/p><p><em>Votre massage<\/em><br \/><strong>Changez-vous en toute intimit\u00e9<\/strong>\u00a0puis\u00a0installez-vous\u00a0sur la table de massage<strong> vous serez recouvert\u00a0d&rsquo;un drap ou d&rsquo;un plaid et profiterez d&rsquo;une table chauffante.\u00a0<\/strong>Votre massage d\u00e9bute par des manoeuvres globales et r\u00e9chauffantes qui pr\u00e9parent le corps au massage<em>. <\/em><strong>Maintenant il est l&rsquo;heure de profiter, puis finissez selon vos envies <\/strong><em>(nuque, visage, tonifiant, relaxant).<\/em><\/p><p><em>Avant de partir\u200b<\/em><br \/><strong>Une fois votre massage termin\u00e9,<\/strong> vous disposez d&rsquo;un moment pour vous laisser le temps d&rsquo;\u00e9merger <strong>\u00e0 votre rythme et reprendre tranquillement vos esprits.<\/strong>\u00a0Suite \u00e0 cela, vous <strong>recevrez un retour\u00a0instructif sur l&rsquo;\u00e9tat de votre corps et ses besoins<\/strong> vous pouvez faire vos retours sur la s\u00e9ance. N&rsquo;oubliez pas que vous pouvez remplir notre livre d&rsquo;or (si vous \u00eates au cabinet) et de laisser un avis Google.<\/p><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"quel-massage-me-convient-le-mieux-\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"3\" aria-controls=\"elementor-tab-content-1693\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">Quel massage me convient le mieux ?<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1693\" class=\"eael-accordion-content clearfix\" data-tab=\"3\" aria-labelledby=\"quel-massage-me-convient-le-mieux-\"><p>Avant tout, il est important d&rsquo;\u00e9couter son corps et ses besoins&#8230;<\/p><ul><li>Si vous avez besoin de vous relaxer je vous conseille de vous dirigez vers un massage cocooning ou bien su\u00e9dois.<br \/><br \/><\/li><li>Si vous avez besoin de vous soulager d&rsquo;une g\u00eane ou d&rsquo;une douleur localis\u00e9e le massage id\u00e9al pour vous est le sp\u00e9cifique.<\/li><\/ul><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"quel-sont-les-horaires-douvertures-\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"4\" aria-controls=\"elementor-tab-content-1694\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">Quel sont les horaires d'ouvertures ?<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1694\" class=\"eael-accordion-content clearfix\" data-tab=\"4\" aria-labelledby=\"quel-sont-les-horaires-douvertures-\"><p>Le cabinet est ouvert* :<\/p><ul><li>Lundi : Ferm\u00e9<\/li><li>Mardi : de 9h \u00e0 12h puis de 14h \u00e0 19h30<\/li><li>Mercredi : de 9h \u00e0 10h30 puis de 14h \u00e0 20h<\/li><li>Jeudi : de 9h \u00e0 18h<\/li><li>Vendredi : de 9h \u00e0 20h<\/li><li>Samedi : de 10h \u00e0 18h<\/li><li>Dimanche : Ferm\u00e9<\/li><\/ul><p><em><br \/>*Sous r\u00e9serve de places disponibles<\/em><\/p><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"quelle-frquence-de-massage-est-idale-\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"5\" aria-controls=\"elementor-tab-content-1695\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">Quelle fr\u00e9quence de massage est id\u00e9ale ?<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1695\" class=\"eael-accordion-content clearfix\" data-tab=\"5\" aria-labelledby=\"quelle-frquence-de-massage-est-idale-\"><p>Cela d\u00e9pend de vos envies et surtout des besoins de votre corps&#8230;<\/p><\/div>\n\t\t\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f25fb4 elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"1f25fb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9feb9bc elementor-widget__width-initial exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"9feb9bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nmmassage.fr\/wp-content\/uploads\/elementor\/thumbs\/NM_LOGOSN-2-ps7m47h518cui67l1dqly3aigmymujeu9iox20kcvk.png\" title=\"Logo NM\" alt=\"NM\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e37d77 elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"2e37d77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac5638a elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"ac5638a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9364cd6 exad-glass-effect-no exad-sticky-section-no\" data-id=\"9364cd6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af0e5fd elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"af0e5fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36df61c elementor-shape-rounded elementor-grid-0 e-grid-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-social-icons\" data-id=\"36df61c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-bounce-out elementor-repeater-item-183c863\" href=\"https:\/\/www.instagram.com\/nmmassage\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-animation-bounce-out elementor-repeater-item-e1ebc3c\" href=\"https:\/\/www.linkedin.com\/in\/nicolas-miramont-927911229\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-bounce-out elementor-repeater-item-1cd3515\" href=\"https:\/\/www.facebook.com\/NM.masseur\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf44eaa elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"cf44eaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17223fa elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"17223fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78bd4c4 exad-glass-effect-no exad-sticky-section-no\" data-id=\"78bd4c4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f82a5a4 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"f82a5a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comment se rendre au cabinet ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-270d2f1 elementor-widget__width-initial exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"270d2f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le cabinet se situe au 144 all\u00e9e George-Sand \u00e0 Bourg-l\u00e8s-Valence 26500<span style=\"font-size: 1rem;\">.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b904d53 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"b904d53\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-02f32d2 exad-glass-effect-no exad-sticky-section-no\" data-id=\"02f32d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88dcbe8 elementor-widget__width-initial elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"88dcbe8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cee2534 elementor-view-default exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon\" data-id=\"cee2534\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"teenyicon ti-car\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7171f69 elementor-widget__width-initial elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"7171f69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a18b232 exad-glass-effect-no exad-sticky-section-no\" data-id=\"a18b232\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2a2169 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"a2a2169\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">En voiture<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f707e1b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"f707e1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous pouvez vous garer sur une place de parking se trouvant\u00a0<span style=\"font-size: 1rem;\">juste devant<\/span><span style=\"font-size: 1rem;\">\u00a0le cabinet.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f34bbbb elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"f34bbbb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-68be20b exad-glass-effect-no exad-sticky-section-no\" data-id=\"68be20b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-574e44f exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"574e44f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">En transport en commun<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff9204e elementor-widget__width-initial exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"ff9204e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous pouvez prendre les bus suivants :&nbsp;<\/p>\n<ul>\n<li>Express 43 &#8211; arr\u00eat Godanger (+ 2min de marche)<\/li>\n<li>C4 &#8211; arr\u00eat Bourg-Blach\u00e8re (+ 4min de marche)<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6234c9d exad-glass-effect-no exad-sticky-section-no\" data-id=\"6234c9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ae82ae elementor-widget__width-initial elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"3ae82ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec111d4 elementor-widget__width-initial elementor-view-default exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon\" data-id=\"ec111d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"remixicon ri-bus-fill\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b48400 elementor-widget__width-initial elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"3b48400\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-18ed0d2 exad-glass-effect-no exad-sticky-section-no\" data-id=\"18ed0d2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3da4b44 elementor-widget__width-initial exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"3da4b44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fa\u00eetes votre propre itin\u00e9raire via Google Maps<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91956c9 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"91956c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nmmassage.fr\/wp-content\/uploads\/elementor\/thumbs\/3-e1705440421834-qievqw13dsw414hjl34fgntciz4sgvwefwh5eh3i7c.png\" title=\"3\" alt=\"3\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0dccae elementor-widget__width-initial exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-google_maps\" data-id=\"f0dccae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyAIsfnJ5KkGYKCra96RYVpfL_A3aoFQLIo&#038;q=144%20all%C3%A9e%20George%20sand%2026500&#038;zoom=15\"\n\t\t\t\t\ttitle=\"144 all\u00e9e George sand 26500\"\n\t\t\t\t\taria-label=\"144 all\u00e9e George sand 26500\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7052bb5 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"7052bb5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37605ef exad-glass-effect-no exad-sticky-section-no\" data-id=\"37605ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4225360 elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"4225360\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vous souhaitez prendre un rendez-vous rapidement ? R\u00e9servez votre massage directement en ligne ! D\u00e9couvrez les cr\u00e9neaux disponibles et r\u00e9servez votre massage en \u00e0 peine 5 minutes gr\u00e2ce \u00e0 Calendly ! Une fois votre demande r\u00e9alis\u00e9e vous recevrez un mail de confirmation. R\u00e9server Vous avez des questions ou une demande particuli\u00e8re ? Contactez-nous directement via [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-822","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact - NMMassage<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nmmassage.fr\/index.php\/contact-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact - NMMassage\" \/>\n<meta property=\"og:description\" content=\"Vous souhaitez prendre un rendez-vous rapidement ? R\u00e9servez votre massage directement en ligne ! D\u00e9couvrez les cr\u00e9neaux disponibles et r\u00e9servez votre massage en \u00e0 peine 5 minutes gr\u00e2ce \u00e0 Calendly ! Une fois votre demande r\u00e9alis\u00e9e vous recevrez un mail de confirmation. R\u00e9server Vous avez des questions ou une demande particuli\u00e8re ? Contactez-nous directement via [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nmmassage.fr\/index.php\/contact-2\/\" \/>\n<meta property=\"og:site_name\" content=\"NMMassage\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-07T09:51:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nmmassage.fr\/wp-content\/uploads\/elementor\/thumbs\/Contact-e1706205062812-qiuaboz84fqnl65bexcunfl661alc79ex7xm0336qk.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nmmassage.fr\\\/index.php\\\/contact-2\\\/\",\"url\":\"https:\\\/\\\/nmmassage.fr\\\/index.php\\\/contact-2\\\/\",\"name\":\"Contact - NMMassage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nmmassage.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nmmassage.fr\\\/index.php\\\/contact-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nmmassage.fr\\\/index.php\\\/contact-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nmmassage.fr\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Contact-e1706205062812-qiuaboz84fqnl65bexcunfl661alc79ex7xm0336qk.png\",\"datePublished\":\"2023-11-13T21:25:53+00:00\",\"dateModified\":\"2024-11-07T09:51:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nmmassage.fr\\\/index.php\\\/contact-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nmmassage.fr\\\/index.php\\\/contact-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nmmassage.fr\\\/index.php\\\/contact-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nmmassage.fr\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Contact-e1706205062812-qiuaboz84fqnl65bexcunfl661alc79ex7xm0336qk.png\",\"contentUrl\":\"https:\\\/\\\/nmmassage.fr\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Contact-e1706205062812-qiuaboz84fqnl65bexcunfl661alc79ex7xm0336qk.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nmmassage.fr\\\/index.php\\\/contact-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/nmmassage.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nmmassage.fr\\\/#website\",\"url\":\"https:\\\/\\\/nmmassage.fr\\\/\",\"name\":\"NMMassage\",\"description\":\"Bien-\u00eatre &amp; Sport\",\"publisher\":{\"@id\":\"https:\\\/\\\/nmmassage.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nmmassage.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nmmassage.fr\\\/#organization\",\"name\":\"NMMassage\",\"url\":\"https:\\\/\\\/nmmassage.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nmmassage.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nmmassage.fr\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/LOGO-N2-e1700668024523.png\",\"contentUrl\":\"https:\\\/\\\/nmmassage.fr\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/LOGO-N2-e1700668024523.png\",\"width\":675,\"height\":363,\"caption\":\"NMMassage\"},\"image\":{\"@id\":\"https:\\\/\\\/nmmassage.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact - NMMassage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nmmassage.fr\/index.php\/contact-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Contact - NMMassage","og_description":"Vous souhaitez prendre un rendez-vous rapidement ? R\u00e9servez votre massage directement en ligne ! D\u00e9couvrez les cr\u00e9neaux disponibles et r\u00e9servez votre massage en \u00e0 peine 5 minutes gr\u00e2ce \u00e0 Calendly ! Une fois votre demande r\u00e9alis\u00e9e vous recevrez un mail de confirmation. R\u00e9server Vous avez des questions ou une demande particuli\u00e8re ? Contactez-nous directement via [&hellip;]","og_url":"https:\/\/nmmassage.fr\/index.php\/contact-2\/","og_site_name":"NMMassage","article_modified_time":"2024-11-07T09:51:28+00:00","og_image":[{"url":"https:\/\/nmmassage.fr\/wp-content\/uploads\/elementor\/thumbs\/Contact-e1706205062812-qiuaboz84fqnl65bexcunfl661alc79ex7xm0336qk.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nmmassage.fr\/index.php\/contact-2\/","url":"https:\/\/nmmassage.fr\/index.php\/contact-2\/","name":"Contact - NMMassage","isPartOf":{"@id":"https:\/\/nmmassage.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nmmassage.fr\/index.php\/contact-2\/#primaryimage"},"image":{"@id":"https:\/\/nmmassage.fr\/index.php\/contact-2\/#primaryimage"},"thumbnailUrl":"https:\/\/nmmassage.fr\/wp-content\/uploads\/elementor\/thumbs\/Contact-e1706205062812-qiuaboz84fqnl65bexcunfl661alc79ex7xm0336qk.png","datePublished":"2023-11-13T21:25:53+00:00","dateModified":"2024-11-07T09:51:28+00:00","breadcrumb":{"@id":"https:\/\/nmmassage.fr\/index.php\/contact-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nmmassage.fr\/index.php\/contact-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nmmassage.fr\/index.php\/contact-2\/#primaryimage","url":"https:\/\/nmmassage.fr\/wp-content\/uploads\/elementor\/thumbs\/Contact-e1706205062812-qiuaboz84fqnl65bexcunfl661alc79ex7xm0336qk.png","contentUrl":"https:\/\/nmmassage.fr\/wp-content\/uploads\/elementor\/thumbs\/Contact-e1706205062812-qiuaboz84fqnl65bexcunfl661alc79ex7xm0336qk.png"},{"@type":"BreadcrumbList","@id":"https:\/\/nmmassage.fr\/index.php\/contact-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/nmmassage.fr\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/nmmassage.fr\/#website","url":"https:\/\/nmmassage.fr\/","name":"NMMassage","description":"Bien-\u00eatre &amp; Sport","publisher":{"@id":"https:\/\/nmmassage.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nmmassage.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nmmassage.fr\/#organization","name":"NMMassage","url":"https:\/\/nmmassage.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nmmassage.fr\/#\/schema\/logo\/image\/","url":"https:\/\/nmmassage.fr\/wp-content\/uploads\/2022\/06\/LOGO-N2-e1700668024523.png","contentUrl":"https:\/\/nmmassage.fr\/wp-content\/uploads\/2022\/06\/LOGO-N2-e1700668024523.png","width":675,"height":363,"caption":"NMMassage"},"image":{"@id":"https:\/\/nmmassage.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nmmassage.fr\/index.php\/wp-json\/wp\/v2\/pages\/822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nmmassage.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nmmassage.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nmmassage.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nmmassage.fr\/index.php\/wp-json\/wp\/v2\/comments?post=822"}],"version-history":[{"count":107,"href":"https:\/\/nmmassage.fr\/index.php\/wp-json\/wp\/v2\/pages\/822\/revisions"}],"predecessor-version":[{"id":2850,"href":"https:\/\/nmmassage.fr\/index.php\/wp-json\/wp\/v2\/pages\/822\/revisions\/2850"}],"wp:attachment":[{"href":"https:\/\/nmmassage.fr\/index.php\/wp-json\/wp\/v2\/media?parent=822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}